{"id":7201,"date":"2024-06-18T15:05:51","date_gmt":"2024-06-18T13:05:51","guid":{"rendered":"https:\/\/intercommerce.si\/izdelek\/pvc-klebebaender\/"},"modified":"2024-06-18T15:05:51","modified_gmt":"2024-06-18T13:05:51","slug":"pvc-klebebaender","status":"publish","type":"product","link":"https:\/\/intercommerce.si\/de\/produkt\/pvc-klebebaender\/","title":{"rendered":"PVC-Klebeb\u00e4nder"},"content":{"rendered":"<p><strong>Eigenschaften von PVC-Klebeb\u00e4ndern<\/strong><\/p>\n<ul>\n<li><strong>Hohe Haltbarkeit<\/strong>: PVC-Klebeb\u00e4nder sind strapazierf\u00e4hig und gew\u00e4hrleisten eine zuverl\u00e4ssige Langzeitnutzung.<\/li>\n<li><strong>Feuchtigkeitsbest\u00e4ndigkeit<\/strong>: Sie eignen sich f\u00fcr den Einsatz in feuchten Umgebungen, da sie bei Feuchtigkeitseinwirkung ihre Klebeeigenschaften nicht verlieren.<\/li>\n<li><strong>Vielfalt an Farben und Breiten<\/strong>: Sie sind in zahlreichen Farben und Breiten erh\u00e4ltlich, was eine Anpassung an spezifische Bed\u00fcrfnisse und Verwendungszwecke erm\u00f6glicht.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"PVC-Klebeb\u00e4nder zeichnen sich im Vergleich zu PP-Klebeb\u00e4ndern durch eine h\u00f6here Festigkeit aus. F\u00fcr eine einfachere Handhabung empfehlen wir einen Handabroller. ","protected":false},"featured_media":4722,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[1813,1823,1846,1881],"product_tag":[],"class_list":["post-7201","product","type-product","status-publish","has-post-thumbnail","product_cat-artikel","product_cat-verpackungsmaterialien","product_cat-klebebander","product_cat-pvc-klebebander","pa_aplikacija-handbuch","pa_aplikacija-hardware","pa_barva-weiss-de","pa_barva-braun","pa_barva-transparent-de","pa_navitje-na-roli-m-66-de","pa_navitje-na-roli-m-132-de","pa_navitje-na-roli-m-660-de","pa_navitje-na-roli-m-990-de","pa_nosilec-pvc-de","pa_sirina-mm-25-de","pa_sirina-mm-50-de","pa_st-izdelkov-v-skatli-36-de","pa_st-izdelkov-v-skatli-6-de","pa_st-izdelkov-v-skatli-72-de","pa_vrsta-lepila-naturkautschuk-losungsmittel","first","instock","product-type-simple"],"acf":[],"gallery_images":[],"_links":{"self":[{"href":"https:\/\/intercommerce.si\/de\/wp-json\/wp\/v2\/product\/7201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intercommerce.si\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/intercommerce.si\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intercommerce.si\/de\/wp-json\/wp\/v2\/media\/4722"}],"wp:attachment":[{"href":"https:\/\/intercommerce.si\/de\/wp-json\/wp\/v2\/media?parent=7201"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/intercommerce.si\/de\/wp-json\/wp\/v2\/product_cat?post=7201"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/intercommerce.si\/de\/wp-json\/wp\/v2\/product_tag?post=7201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}